{"id":93934,"date":"2024-05-11T05:47:58","date_gmt":"2024-05-11T05:47:58","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=93934"},"modified":"2024-05-11T05:47:59","modified_gmt":"2024-05-11T05:47:59","slug":"carin-leon-ofrecera-concierto-gratis-en-monterrey","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/carin-leon-ofrecera-concierto-gratis-en-monterrey\/","title":{"rendered":"Car\u00edn Le\u00f3n ofrecer\u00e1 concierto gratis en Monterrey"},"content":{"rendered":"<p>Monterrey. &#8211; El gobernador Samuel Garc\u00eda anunci\u00f3 que para el MacroFest estar\u00e1 como invitado el cantante Car\u00edn Le\u00f3n.<\/p>\n<p>Fue mediante su cuenta de Facebook que Garc\u00eda Sep\u00falveda anunci\u00f3 la noticia.<\/p>\n<p>\u201cAh\u00ed les va una sorpresota a las mam\u00e1s en su d\u00eda: Mi compadre Car\u00edn Le\u00f3n se viene al Macrofest. \u00a1Agarren sombrero y botas! Recuerden que es completamente gratis\u201d, escribi\u00f3.<\/p>\n<p>Mencion\u00f3 que el concierto ser\u00e1 el pr\u00f3ximo 19 de mayo en la Macroplaza, sin embargo, no dio horario.<\/p>\n<p>\u00bfQui\u00e9n es Car\u00edn Le\u00f3n?<br \/>\nCar\u00edn Le\u00f3n es un cantante de m\u00fasica regional mexicana, espec\u00edficamente del g\u00e9nero de banda y corridos. Es conocido por \u00e9xitos como &#8220;Me La Avent\u00e9&#8221;, &#8220;T\u00fa&#8221;, &#8220;Borracho de Por Vida&#8221;, entre otros.<\/p>\n<p>Cantar\u00e1 Car\u00edn Le\u00f3n himno de M\u00e9xico en pelea Canelo-Bivol<br \/>\nNaci\u00f3 en Hermosillo, Sonora, M\u00e9xico, y debut\u00f3 como solista en 2018, luego de integrar la banda Grupo Arranke.<\/p>\n<p>El mexicano brill\u00f3 al lado del colombiano Maluma en la pasada gala de los Latin Grammy que se llevaron a cabo en Sevilla, Espa\u00f1a.<\/p>\n<p>\u00d3scar Armando D\u00edaz De Le\u00f3n Huez, mejor conocido en el mundo art\u00edstico como Car\u00edn Le\u00f3n, se ha posicionado como una figura importante en la m\u00fasica regional mexicana.<\/p>\n<p>Adem\u00e1s, su estilo musical es popular entre los seguidores de la m\u00fasica regional mexicana y ha ganado una considerable base de fan\u00e1ticos.<\/p>\n<p>Ha colaborado con Grupo Firme, Camilo, Pablo Albor\u00e1n, \u00c1ngela Aguilar, Diego Verdaguer, Pancho Barraza, C. Tangana, Matisse, Espinoza Paz y compuesto para artistas como Christian Nodal, entre otros.<br \/>\n<!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey. &#8211; El gobernador Samuel Garc\u00eda anunci\u00f3 que para el MacroFest estar\u00e1 como invitado el cantante Car\u00edn Le\u00f3n. Fue mediante su cuenta de Facebook que Garc\u00eda Sep\u00falveda anunci\u00f3 la noticia. \u201cAh\u00ed les va una sorpresota a las mam\u00e1s en su [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":93937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[66],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/93934"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=93934"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/93934\/revisions"}],"predecessor-version":[{"id":93938,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/93934\/revisions\/93938"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/93937"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=93934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=93934"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=93934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}