{"id":93901,"date":"2024-05-10T02:11:33","date_gmt":"2024-05-10T02:11:33","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=93901"},"modified":"2024-05-10T02:11:34","modified_gmt":"2024-05-10T02:11:34","slug":"mama-apunala-a-sus-bebes-recien-nacidas-en-hospital-de-ensenada-una-murio","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/mama-apunala-a-sus-bebes-recien-nacidas-en-hospital-de-ensenada-una-murio\/","title":{"rendered":"Mam\u00e1 apu\u00f1ala a sus beb\u00e9s reci\u00e9n nacidas en hospital de Ensenada; una muri\u00f3"},"content":{"rendered":"\n<p>Baja California. &#8211; Una mam\u00e1 apu\u00f1al\u00f3 a sus beb\u00e9s reci\u00e9n nacidas al interior de un hospital en Ensenada, Baja California.<\/p>\n\n\n\n<p>De acuerdo a medios nacionales, una de las infantes muri\u00f3, mientras que la otra se encuentra en estado grave.<\/p>\n\n\n\n<p>Los hechos se reportaron en el Hospital 8 del Instituto Mexicano del Seguro Social (IMSS) ayer mi\u00e9rcoles 8 de mayo.<\/p>\n\n\n\n<p>La Delegada del IMSS en Baja California, Desir\u00e9e Sagarnaga, inform\u00f3 que las beb\u00e9s fueron agredidas con unas tijeras despu\u00e9s de que la madre fuera dada de alta del hospital.<\/p>\n\n\n\n<p>\u201cNo sabemos con exactitud c\u00f3mo pudo apropiarse de esas tijeras. Estamos investigando justamente con las autoridades para que quede bien claro c\u00f3mo es que se hizo de esas tijeras\u201d, refiri\u00f3.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La mujer aprovech\u00f3 que el padre de familia no se encontraba en la habitaci\u00f3n, para atacar a sus hijas.<\/p>\n\n\n\n<p>Una de las menores falleci\u00f3, mientras que la otra permanece en estado grave de salud debido a que ambos pulmones fueron perforados.<\/p>\n\n\n\n<p>Personal m\u00e9dico dio a conocer que durante 48 horas las ni\u00f1as permanecieron con su madre y las amamant\u00f3 con cari\u00f1o.<\/p>\n\n\n\n<p>La agresora, una joven de 23 a\u00f1os, est\u00e1 bajo custodia y atenci\u00f3n m\u00e9dica en el hospital, mientras que el padre ha sido trasladado a la Fiscal\u00eda del Estado para declarar ante el Ministerio P\u00fablico.<\/p>\n\n\n\n<p>Mujer arroja a su hijo con discapacidad a r\u00edo infestado de cocodrilos en India<br>Una joven madre de familia arroj\u00f3 a un r\u00edo lleno de cocodrilos a su hijo de seis a\u00f1os, quien sufr\u00eda de una discapacidad, en la India.<\/p>\n\n\n\n<p>El acto de violencia contra el menor de edad sucedi\u00f3 el pasado 4 de mayo en el distrito de Uttara Kannada, luego de una discusi\u00f3n marital, detall\u00f3 el diario Times of India.<\/p>\n\n\n\n<p>Luego de que el ni\u00f1o fuera enviado a este canal de desperdicios, que conecta directamente con el r\u00edo Kali, vecinos que fueron testigos del hecho hicieron el reporte a la polic\u00eda.<\/p>\n\n\n\n<p>Minutos despu\u00e9s se dio el arribo de los efectivos, quienes, con ayuda de buzos y mismos lugare\u00f1os, encabezaron un operativo de b\u00fasqueda del menor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Baja California. &#8211; Una mam\u00e1 apu\u00f1al\u00f3 a sus beb\u00e9s reci\u00e9n nacidas al interior de un hospital en Ensenada, Baja California. De acuerdo a medios nacionales, una de las infantes muri\u00f3, mientras que la otra se encuentra en estado grave. Los [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":93904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/93901"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=93901"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/93901\/revisions"}],"predecessor-version":[{"id":93905,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/93901\/revisions\/93905"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/93904"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=93901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=93901"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=93901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}