{"id":93601,"date":"2024-05-06T05:20:30","date_gmt":"2024-05-06T05:20:30","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=93601"},"modified":"2024-05-06T05:20:31","modified_gmt":"2024-05-06T05:20:31","slug":"habia-un-libro-con-recetas-macabros-hallazgos-en-una-casa-de-canibales","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/habia-un-libro-con-recetas-macabros-hallazgos-en-una-casa-de-canibales\/","title":{"rendered":"\u201cHab\u00eda un libro con recetas\u201d: Macabros hallazgos en una casa de can\u00edbales"},"content":{"rendered":"<p>RUSIA.- Los nombres de Dmitry Baksheev y Natalia Baksheeva siguen causando terror entre los habitantes de Krasnodar, una ciudad ubicada al suroeste de Rusia. La pareja caus\u00f3 conmoci\u00f3n, en todo el mundo, luego de que fueron arrestados en el a\u00f1o 2017, despu\u00e9s de que las autoridades rusas los identificaron como asesinos y can\u00edbales, involucrados en la masacre de al menos 30 personas. Ahora, a casi 7 a\u00f1os de su detenci\u00f3n, los habitantes del pa\u00eds siguen sorprendi\u00e9ndose con los macabros hallazgos que se han encontrado dentro de su departamento \u201cde terror\u201d, donde mataban y cocinaban a sus v\u00edctimas.<\/p>\n<p>Seg\u00fan las autoridades rusas, dentro del departamento, ubicado en la ciudad de Krasnodar, Natalia y Dmitry almacenaban restos humanos, los cuales supuestamente cocinaban para posteriormente alimentarse.<\/p>\n<p>La pareja incluso ten\u00eda un libro de recetas que involucraban platillos con carne humana; por si fuera poco, la polic\u00eda tambi\u00e9n incaut\u00f3 videos filmados por el matrimonio, donde ambos explicaban el paso a paso para cocinar carne de seres humanos.<\/p>\n<p>Usaban apps de citas para conseguir v\u00edctimas<\/p>\n<p>De acuerdo con la informaci\u00f3n oficial del caso, la pareja consegu\u00eda a sus v\u00edctimas a trav\u00e9s de aplicaciones de citas. Dmitry, quien durante su juicio fue apodado por la sociedad como \u201cDiablo\u201c, era quien contactaba a mujeres y les propon\u00eda encuentros, para posteriormente asesinarlas en compa\u00f1\u00eda y colaboraci\u00f3n de Natalia. Ambos estuvieron operando durante a\u00f1os, hasta que finalmente fueron arrestados \u2013 en 2017 \u2013 por el homicidio de una mesera; la polic\u00eda ejecut\u00f3 la orden de aprehensi\u00f3n sin saber los horrores que se escond\u00edan en su vivienda.<\/p>\n<p>La \u00faltima v\u00edctima de la pareja fue una mujer llamada Elena Vashrusheva, de 35 a\u00f1os, quien viv\u00eda en el mismo edificio que ellos. La v\u00edctima acudi\u00f3, en septiembre de 2017, a casa de los can\u00edbales, donde fue asesinada y mutilada. Su desaparici\u00f3n era investigada por las autoridades, cuando un trabajador de limpieza encontr\u00f3 en la calle el celular de Dmitry, quien lo perdi\u00f3 por accidente; el hombre abri\u00f3 la galer\u00eda de fotos del m\u00f3vil y encontr\u00f3 fotograf\u00edas de el \u201cDiablo\u201d con los restos humanos de la camarera desaparecida.<\/p>\n<p>As\u00ed fue la ca\u00edda de los can\u00edbales de Krasnodar: \u00e9l muri\u00f3 y ella saldr\u00e1 en libertad<\/p>\n<p>El trabajador llev\u00f3 el celular ante las autoridades, quienes identificaron a Dmitry y acudieron a su domicilio para arrestarlo. No obstante, cuando los polic\u00eda acudieron a la vivienda encontraron una escena horrible: los restos de Elena estaban en el congelador y hab\u00eda platillos con carne humana en la mesa de la pareja.<\/p>\n<p>Por este atroz homicidio el \u201cDiablo\u201d y Natalia fueron detenidos y enfrentaron un juicio en su contra. En sus audiencias, Dmitry confes\u00f3 que comenz\u00f3 su macabro reinado de terror en 1999 junto a su esposa Natalia, quien identific\u00f3 a docenas de mujeres que dijo haber asesinado con su marido.<\/p>\n<p>Seg\u00fan medios rusos, Dmitry fue encarcelado y sentenciado a 13 a\u00f1os por el asesinato de Elena. Sin embargo, en 2019 las autoridades rusas realizaron otro juicio en su contra, pero el hombre muri\u00f3 por tuberculosis en una colonia penal durante 2020, sin que recibiera otra pena por sus horribles cr\u00edmenes.<\/p>\n<p>Por su parte, Natalia recibi\u00f3 11 a\u00f1os de prisi\u00f3n por la muerte de Elena; ya que, hasta ahora, la mujer no ha recibido otra acusaci\u00f3n en su contra, se espera que salga en libertad en el a\u00f1o 2029, cuando tenga 54 a\u00f1os de edad.<br \/>\n<!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>RUSIA.- Los nombres de Dmitry Baksheev y Natalia Baksheeva siguen causando terror entre los habitantes de Krasnodar, una ciudad ubicada al suroeste de Rusia. La pareja caus\u00f3 conmoci\u00f3n, en todo el mundo, luego de que fueron arrestados en el a\u00f1o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":93604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[61],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/93601"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=93601"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/93601\/revisions"}],"predecessor-version":[{"id":93605,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/93601\/revisions\/93605"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/93604"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=93601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=93601"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=93601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}