{"id":75242,"date":"2023-08-16T19:24:31","date_gmt":"2023-08-16T19:24:31","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=75242"},"modified":"2023-08-16T19:24:33","modified_gmt":"2023-08-16T19:24:33","slug":"lanzan-album-de-vicente-fernandez-con-canciones-que-grabo-antes-de-morir","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/lanzan-album-de-vicente-fernandez-con-canciones-que-grabo-antes-de-morir\/","title":{"rendered":"Lanzan \u00e1lbum de Vicente Fern\u00e1ndez con canciones que grab\u00f3 antes de morir"},"content":{"rendered":"<p>M\u00c9XICO.- Vicente Fern\u00e1ndez muri\u00f3 en diciembre del 2021 y sin duda fue una gran p\u00e9rdida para la m\u00fasica en M\u00e9xico y en el mundo. A pesar de que el cantante se retir\u00f3 de los escenarios varios a\u00f1os antes de su muerte, dej\u00f3 grabadas 200 canciones, algunas de ellas se encuentran en un \u00e1lbum p\u00f3stumo que hace poco fue lanzado.<\/p>\n<p>Hace unos d\u00edas la familia del Charro de Huentit\u00e1n anunci\u00f3 Vicente Fern\u00e1ndez Le Canta A Los Grandes Compositores de M\u00e9xico, el disco p\u00f3stumo del cantante que contiene canciones in\u00e9ditas interpretadas con la gran voz que ten\u00eda el padre de Alejandro Fern\u00e1ndez.<\/p>\n<p>Por medio de un video compartido en el Instagram de Vicente Fern\u00e1ndez, se ve al cantante dando un mensaje a sus fans y despu\u00e9s el anuncio del disco.<\/p>\n<p>\u201cEl d\u00eda que me retir\u00e9 del Estadio Azteca, les dije que me retirar\u00eda de los escenarios, pero que seguir\u00eda grabando mis videos y cantado en mi compa\u00f1\u00eda para que ustedes no me dejaran de querer y no me olvidaran\u201d.<br \/>\nEl disco p\u00f3stumo de Vicente Fern\u00e1ndez cuenta con 20 canciones, 10 de ellas son in\u00e9ditas. Tal y como el nombre del \u00e1lbum menciona, el cantante grab\u00f3 algunos de los temas m\u00e1s conocidos de importantes compositores de M\u00e9xico.<\/p>\n<p>Algunas de las canciones que componen el \u00e1lbum son: Aquel Amor de Agust\u00edn Lara, Aunque tengas raz\u00f3n escrita por Consuelo Vel\u00e1zquez, Te parto el alma de Cuco S\u00e1nchez y La media Vuelta de Jos\u00e9 Alfredo Jim\u00e9nez.<\/p>\n<p>De acuerdo con la familia de Vicente Fern\u00e1ndez, el cantante dej\u00f3 grabadas cerca de 200 canciones antes de morir y se tomaron 20 de ellas para incorporarlas al disco.<\/p>\n<p>Entre otras canciones que tiene el disco p\u00f3stumo de Vicente Fern\u00e1ndez se encuentran: Amor de los dos de Gilberto Parra, La Diferencia de Juan Gabriel, as\u00ed como Un mill\u00f3n de Primaveras de Joan Sebasti\u00e1n, con quien el cantante trabaj\u00f3 en su disco Para Siempre.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00c9XICO.- Vicente Fern\u00e1ndez muri\u00f3 en diciembre del 2021 y sin duda fue una gran p\u00e9rdida para la m\u00fasica en M\u00e9xico y en el mundo. A pesar de que el cantante se retir\u00f3 de los escenarios varios a\u00f1os antes de su [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":75245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[66],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/75242"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=75242"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/75242\/revisions"}],"predecessor-version":[{"id":75246,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/75242\/revisions\/75246"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/75245"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=75242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=75242"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=75242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}