{"id":74112,"date":"2023-07-31T20:25:46","date_gmt":"2023-07-31T20:25:46","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=74112"},"modified":"2023-07-31T20:25:48","modified_gmt":"2023-07-31T20:25:48","slug":"adn-identifica-a-homicida-de-nina-30-anos-despues-en-florida","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/adn-identifica-a-homicida-de-nina-30-anos-despues-en-florida\/","title":{"rendered":"ADN identifica a homicida de ni\u00f1a, 30 a\u00f1os despu\u00e9s, en Florida"},"content":{"rendered":"<p>Estados Unidos.-  Jennifer Odom ten\u00eda 12 a\u00f1os cuando fue encontrada muerta en un campo de naranjos de Florida en 1993; 30 a\u00f1os despu\u00e9s lograron identificar a su asesino.<\/p>\n<p>De acuerdo a las autoridades del condado Hernando fue una coincidencia de ADN que identific\u00f3 al responsable.<\/p>\n<p>El fiscal estatal Bill Gladson se\u00f1al\u00f3 que el acusado, identificado como Jeffrey Norman, de 61 a\u00f1os, ahora puede enfrentar la pena de muerte.<\/p>\n<p>El hombre actualmente cumple dos cadenas perpetuas por agresi\u00f3n sexual e intento de asesinato en 2015.<\/p>\n<p>\u201cEsta es la pesadilla de todos los padres. Conf\u00edo en que tenemos a la persona adecuada y tenemos los agravantes adecuados para tratarlo como un caso de pena de muerte\u201d, agreg\u00f3.<\/p>\n<p>\u00bfQu\u00e9 le pas\u00f3 a Jennifer Odom?<br \/>\nJennifer desapareci\u00f3 el 19 de febrero de 1993, luego de bajarse del autob\u00fas escolar alrededor de las 3 de la tarde en el condado Pasco.<\/p>\n<p>Luego de saludar a sus amigos comenz\u00f3 a caminar unos 183 metros hacia su casa, pero nunca lleg\u00f3.<\/p>\n<p>Los ni\u00f1os que se encontraban en el autob\u00fas, se\u00f1alaron a la polic\u00eda que vieron una camioneta azul que segu\u00eda lentamente a Jennifer mientras caminaba hacia su casa.<\/p>\n<p>Despu\u00e9s de seis d\u00edas, su cuerpo fue localizado en un campo de naranjos en el condado Hernando.<\/p>\n<p>Seg\u00fan la autoridad, el responsable tiene un historial de delitos violentos, incluido un robo en 1981 y un caso de agresi\u00f3n sexual en 1985 en Hillsborough<\/p>\n<p>&#8220;No es alguien a quien deba tomarse a la ligera, este es un tipo malo que disfrutaba de la violencia\u201d, dijo el jefe de polic\u00eda del condado Hernando, Al Nienhuis.<\/p>\n<p>\u00bfC\u00f3mo identific\u00f3 la polic\u00eda el ADN?<br \/>\nEl  jefe de polic\u00eda del condado Hernando, Al Nienhuis, se\u00f1al\u00f3 que el ADN recolectado del caso anterior de agresi\u00f3n sexual de Crum les dio la evidencia que necesitaban para acusarlo del asesinato de Jennifer.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos.- Jennifer Odom ten\u00eda 12 a\u00f1os cuando fue encontrada muerta en un campo de naranjos de Florida en 1993; 30 a\u00f1os despu\u00e9s lograron identificar a su asesino. De acuerdo a las autoridades del condado Hernando fue una coincidencia de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":74115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[61],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/74112"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=74112"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/74112\/revisions"}],"predecessor-version":[{"id":74116,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/74112\/revisions\/74116"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/74115"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=74112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=74112"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=74112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}