{"id":71333,"date":"2023-06-19T19:49:03","date_gmt":"2023-06-19T19:49:03","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=71333"},"modified":"2023-06-19T19:49:04","modified_gmt":"2023-06-19T19:49:04","slug":"nino-cae-de-azotea-tras-intentar-ver-fiesta-de-peso-pluma","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/nino-cae-de-azotea-tras-intentar-ver-fiesta-de-peso-pluma\/","title":{"rendered":"Ni\u00f1o cae de azotea tras intentar ver fiesta de Peso Pluma"},"content":{"rendered":"<p>Guadalajara.- El cantante Hassan Kabande Laija, quien es mejor conocido como Peso Pluma, cumpli\u00f3 sus 24 a\u00f1os el pasado jueves y se festej\u00f3 a lo grande en Guadalajara, de donde es originario.<\/p>\n<p>Erick Arag\u00f3n, Luis R. Conriquez y Jasiel Nu\u00f1ez, fueron sus invitados de lujo, quienes disfrutaron al m\u00e1ximo de la velada. El artista aprovech\u00f3 la ocasi\u00f3n para deleitar a los asistentes con algunas de sus canciones, incluyendo su \u00e9xito &#8220;Rosa Pastel&#8221;, que forma parte de su nuevo \u00e1lbum titulado &#8220;G\u00e9nesis&#8221;.<\/p>\n<p>Sin embargo, en medio del festejo, un peque\u00f1o fan del int\u00e9rprete de \u2018corridos b\u00e9licos\u00b4 de alrededor de 10 a\u00f1os de edad sufri\u00f3 un accidente.<\/p>\n<p>Un ni\u00f1o cay\u00f3 de la azotea de su casa al intentar ver la fiesta de cumplea\u00f1os de Hassan Kabande, el menor quien fu e identificado como Axel, tuvo que ser trasladado de emergencia al hospital m\u00e1s cercano debido a los golpes que sufri\u00f3 por la ca\u00edda.<\/p>\n<p>De acuerdo con medio nacionales, Axel se subi\u00f3 al techo de su casa para acercarse a la ventana de su vecino y desde ah\u00ed poder ver el festejo de su \u00eddolo, sin embargo, se resbal\u00f3 y se cay\u00f3 de la azotea<\/p>\n<p>Los padres del menor revelaron que su ni\u00f1o es muy fan de Peso Pluma, por lo que al enterarse de que Kabande Laija estar\u00eda festej\u00e1ndose a pocas casas de su domicilio, intent\u00f3 hacer todo lo posible por verlo.<\/p>\n<p>Al sitio arribaron param\u00e9dicos para auxiliar al ni\u00f1o, quien fue encontrado con vida pese hacer ca\u00eddo desde una altura considerable, de aproximadamente 5 metros.<\/p>\n<p>El personal m\u00e9dico que lo atendi\u00f3 dio a conocer que el menor result\u00f3 con heridas graves en su cara, lo llevaron de inmediato a una cl\u00ednica cercana para que lo atendieran, pero debido a la gravedad de las lesiones, fue trasladado de emergencia a un hospital, en donde tuvo que ser intubado.<\/p>\n<p>Axel fue reportado como grave de salud, sin embargo, hasta el momento no se han dado a conocer m\u00e1s detalles sobre la evoluci\u00f3n de su recuperaci\u00f3n.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guadalajara.- El cantante Hassan Kabande Laija, quien es mejor conocido como Peso Pluma, cumpli\u00f3 sus 24 a\u00f1os el pasado jueves y se festej\u00f3 a lo grande en Guadalajara, de donde es originario. Erick Arag\u00f3n, Luis R. Conriquez y Jasiel Nu\u00f1ez, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":71335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/71333"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=71333"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/71333\/revisions"}],"predecessor-version":[{"id":71336,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/71333\/revisions\/71336"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/71335"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=71333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=71333"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=71333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}