{"id":70564,"date":"2023-06-05T19:13:08","date_gmt":"2023-06-05T19:13:08","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=70564"},"modified":"2023-06-05T19:13:08","modified_gmt":"2023-06-05T19:13:08","slug":"nuevo-leon-tercer-lugar-en-feminicidios-a-nivel-nacional","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/nuevo-leon-tercer-lugar-en-feminicidios-a-nivel-nacional\/","title":{"rendered":"Nuevo Le\u00f3n, tercer lugar en feminicidios a nivel nacional"},"content":{"rendered":"<p>Monterrey.- La violencia contra las mujeres en Nuevo Le\u00f3n, cada vez va m\u00e1s al alza, principalmente en delitos como desaparici\u00f3n, acoso, abuso sexual, violencia familiar y feminicidios, lo que coloca a nuestra entidad dentro de los primeros lugares a nivel nacional en violencia de g\u00e9nero.<\/p>\n<p>De acuerdo con datos publicados por el Secretariado Ejecutivo del Sistema de Seguridad P\u00fablica, con corte de enero al mes de abril del 2023, de los 281 feminicidios cometidos a nivel nacional, en Nuevo Le\u00f3n, se han registrado 22, coloc\u00e1ndolo en tercer lugar.<\/p>\n<p>Adem\u00e1s, Nuevo Le\u00f3n, cuenta con seis de los municipios con m\u00e1s feminicidios a nivel nacional; poniendo a Guadalupe, Ju\u00e1rez, Escobedo, Cadereyta, Ci\u00e9nega de Flores y Monterrey en los primeros lugares.<\/p>\n<p>Ciudadanos en Apoyo a los Derechos Humanos, publicaron un bolet\u00edn el pasado mes de marzo en el marco del 8M, en el que informan que el 68.1% de las mujeres en el estado, ha experimentado alg\u00fan tipo de violencia.<\/p>\n<p>En el Sistema de Seguridad P\u00fablica, tambi\u00e9n se registr\u00f3 que Nuevo Le\u00f3n, ocupa el tercer lugar en delitos por violaci\u00f3n, con 519 casos de 7 mil 730.<br \/>\nEn delitos de violencia familiar, se coloc\u00f3 en tercer lugar con 6 mil 600 casos y en v\u00edctimas de trata de personas en s\u00e9ptimo lugar con 14 casos.<\/p>\n<p>En la \u00faltima Evaluaci\u00f3n de \u00bfC\u00f3mo Vamos Nuevo Le\u00f3n?, con corte al mes de marzo 2023 a los alcaldes metropolitanos, los homicidios aumentaron un 37 por ciento en comparaci\u00f3n con \u00e9l inici\u00f3 de las administraciones.<\/p>\n<p>Los municipios donde hubo mayores incrementos fueron: Santa Catarina con 77.5%, Monterrey con 50.8% y Escobedo 43.1%. De igual forma, los delitos sexuales aumentaron 15% con aumentos de119% en Ju\u00e1rez, 98% en Escobedo y 93% en Santa Catarina.<\/p>\n<p>Al respecto, Luis \u00c1vila, director del organismo, detall\u00f3 que este tema sigue siendo el tal\u00f3n de Aquiles de los municipios y el reto ser\u00e1 abatir la impunidad en estos delitos.<\/p>\n<p>\u201cEs preocupante que los delitos con violencia en particular homicidios se mantengan con una tendencia al alza y exige que entre las autoridades no s\u00f3lo profundicen en las estrategias de coordinaci\u00f3n de abatir la impunidad en estos delitos y eso los obliga a coordinarse entre ellos y mantener una coordinaci\u00f3n adecuada entre el estado y la fiscal\u00eda, lo cual debe ser una de las prioridades en nuestra ciudad para el siguiente semestre\u201d, precis\u00f3 el director.<\/p>\n<p>De acuerdo con datos de la Fiscal\u00eda General de Justicia del Estado, en el 2022 se registraron 102 asesinatos, la cifra m\u00e1s alta desde que el feminicidio fue incluido en el c\u00f3digo penal estatal y superando en un 65 por ciento a los feminicidios cometidos en el 2021, que cerr\u00f3 con 66.<\/p>\n<p>El creciente aumento de violencia contra las mujeres y homicidios se da en medio de una lucha de poderes entre los legisladores locales, alcaldes y el gobernador, Samuel Garc\u00eda.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey.- La violencia contra las mujeres en Nuevo Le\u00f3n, cada vez va m\u00e1s al alza, principalmente en delitos como desaparici\u00f3n, acoso, abuso sexual, violencia familiar y feminicidios, lo que coloca a nuestra entidad dentro de los primeros lugares a nivel [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":70566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/70564"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=70564"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/70564\/revisions"}],"predecessor-version":[{"id":70567,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/70564\/revisions\/70567"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/70566"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=70564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=70564"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=70564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}