{"id":66847,"date":"2023-03-22T04:17:53","date_gmt":"2023-03-22T04:17:53","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=66847"},"modified":"2023-03-22T04:17:54","modified_gmt":"2023-03-22T04:17:54","slug":"es-antidemocratico-amlo-sobre-posible-arresto-a-donald-trump","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/es-antidemocratico-amlo-sobre-posible-arresto-a-donald-trump\/","title":{"rendered":"Es antidemocr\u00e1tico: AMLO sobre posible arresto a Donald Trump"},"content":{"rendered":"\n<p>Ciudad de M\u00e9xico. &#8211; El presidente, Andr\u00e9s Manuel L\u00f3pez Obrador, consider\u00f3 &#8220;antidemocr\u00e1tico&#8221; el posible arresto este martes del exmandatario estadounidense Donald Trump (2017-2021) por el pago de dinero para silenciar a la actriz de cine porno Stormy Daniels.<\/p>\n\n\n\n<p>\u201cEst\u00e1 declarando el presidente Trump, el expresidente Trump, que lo van a detener, creo que hoy, por un asunto presuntamente amoroso. Si fuese as\u00ed, pues todo mundo sabr\u00eda, porque no nos estamos chupando el dedo, que es para que no aparezca en la boleta electoral&#8221;, expres\u00f3 el gobernante mexicano en su rueda de prensa diaria.<\/p>\n\n\n\n<p>El presidente de M\u00e9xico hizo estas declaraciones mientras Trump ha convocado a protestas por su supuesto arresto este martes por una investigaci\u00f3n de Manhattan sobre un pago de 130 mil d\u00f3lares a Stormy Daniels presuntamente a cambio de su silencio sobre una relaci\u00f3n sexual durante la campa\u00f1a para las elecciones de 2016.<\/p>\n\n\n\n<p>Trump ha denunciado una &#8220;caza de brujas&#8221; y acus\u00f3 el domingo a su sucesor, Joe Biden, de estar implicado en la investigaci\u00f3n en su contra por parte de la Fiscal\u00eda de Manhattan que ha durado cerca de cinco a\u00f1os.<\/p>\n\n\n\n<p>L\u00f3pez Obrador, quien antes ha presumido de su &#8220;muy buena relaci\u00f3n&#8221; con Trump, hizo eco de las voces en Estados Unidos que tachan el caso de una &#8220;persecuci\u00f3n pol\u00edtica&#8221;.<\/p>\n\n\n\n<p>Andr\u00e9s Manuel L\u00f3pez Obrador en reuni\u00f3n con Donald Trump | Archivo ABC Noticias<br>&#8220;Eso es completamente antidemocr\u00e1tico porque no se le permite al pueblo que sea el que decida, pero todo esto (lo digo) en plan de amigos&#8221;, coment\u00f3 en su conferencia, que se realiz\u00f3 en el sure\u00f1o estado de Oaxaca.<\/p>\n\n\n\n<p>El mandatario mexicano ha causado pol\u00e9mica antes por su respaldo a alegatos de Trump, como en las elecciones estadounidenses de 2016, cuando retras\u00f3 su reconocimiento a la victoria de Biden por las denuncias de fraude del candidato republicano, algo que compar\u00f3 con lo que \u00e9l dice que padeci\u00f3 en las elecciones mexicanas de 2006.<\/p>\n\n\n\n<p>En esta ocasi\u00f3n, L\u00f3pez Obrador compar\u00f3 la situaci\u00f3n de Trump con el desafuero que \u00e9l vivi\u00f3 como jefe de Gobierno del Distrito Federal en 2004 y 2005, cuando el Gobierno del entonces presidente Vicente Fox (2000-2006) pidi\u00f3 quitarle su inmunidad pol\u00edtica por el presunto caso de una expropiaci\u00f3n ilegal de un terreno.<\/p>\n\n\n\n<p>&#8220;Si digo esto es porque yo padec\u00ed de la fabricaci\u00f3n de un delito porque no quer\u00edan que yo fuese candidato (a la presidencia)&#8221;, indic\u00f3 el gobernante mexicano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico. &#8211; El presidente, Andr\u00e9s Manuel L\u00f3pez Obrador, consider\u00f3 &#8220;antidemocr\u00e1tico&#8221; el posible arresto este martes del exmandatario estadounidense Donald Trump (2017-2021) por el pago de dinero para silenciar a la actriz de cine porno Stormy Daniels. \u201cEst\u00e1 declarando [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":66849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/66847"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=66847"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/66847\/revisions"}],"predecessor-version":[{"id":66850,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/66847\/revisions\/66850"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/66849"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=66847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=66847"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=66847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}