{"id":66292,"date":"2023-03-09T06:09:20","date_gmt":"2023-03-09T06:09:20","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=66292"},"modified":"2023-03-09T06:09:21","modified_gmt":"2023-03-09T06:09:21","slug":"victoria-en-numeros-rojos-por-falta-de-agua-gattas%ef%bf%bc","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/victoria-en-numeros-rojos-por-falta-de-agua-gattas%ef%bf%bc\/","title":{"rendered":"Victoria en n\u00fameros rojos por falta de agua: Gatt\u00e1s\ufffc"},"content":{"rendered":"<p>VICTORIA, TAM.- En estos momentos Ciudad Victoria vive una emergencia de n\u00fameros rojos por el tema del agua, se est\u00e1 dando prioridad a hospitales y escuelas, el gobierno del estado dotar\u00e1 de m\u00e1s pipas para suministrar del vital l\u00edquido a m\u00e1s colonias, reconoci\u00f3 este mi\u00e9rcoles el alcalde Eduardo Gatt\u00e1s B\u00e1ez.<\/p>\n<p>Dijo que, \u201csi es una emergencia, pero es una emergencia de numero rojo, reci\u00e9n salimos con una campa\u00f1a denominada \u201cCi\u00e9rrale Pelao\u201d, donde le pedimos al ciudadano que cuide el agua, que no lave las camionetas con la manguera, el problema es grave, hemos tapado casi todas las fugas, son m\u00ednimas las que hay, llegamos a estar tapando 60 fugas por semana ahorita es m\u00ednimo y en las colonias por la periferia\u201d.<\/p>\n<p>Resalt\u00f3 que \u201cEn la mesa del agua se da prioridad a los hospitales y a los centros escolares, este a\u00f1o vamos a concluir 30 cisternas en escuelas primarias y secundarias de la periferia donde ya dif\u00edcilmente les podemos llevar el agua por tuber\u00eda, estamos trabajando, estamos dotando de agua a la mayor\u00eda de las escuelas de Victoria\u201d.<\/p>\n<p>Destac\u00f3 que en una revisi\u00f3n reciente arroj\u00f3 que \u201csolamente son 21 colonias las que no tienen agua, a las que estamos dotando del vital liquido por pipa, hay otras 20 que son asentamientos irregulares, son personas que se instalaron en \u00e1reas donde los estudios de factibilidad no nos dan para introducir el agua, no tienen ni luz, pero si se les dota de agua en pipas y con ello atender sus necesidades\u201d.<\/p>\n<p>Confirm\u00f3 que ante esta situaci\u00f3n, el gobierno del estado va a ayudar con m\u00e1s pipas, \u201cva a haber pipas para dotar de agua a las casas nos van dar unas pipas para riego de agua tratada y en cuanto al tema del acueducto el proyecto del acueducto del Panuco no va ser para Nuevo Le\u00f3n, pero sigue el proyecto para Tamaulipas, ser\u00eda trasvase en nuestra presa\u201d.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VICTORIA, TAM.- En estos momentos Ciudad Victoria vive una emergencia de n\u00fameros rojos por el tema del agua, se est\u00e1 dando prioridad a hospitales y escuelas, el gobierno del estado dotar\u00e1 de m\u00e1s pipas para suministrar del vital l\u00edquido a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":66294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[59],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/66292"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=66292"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/66292\/revisions"}],"predecessor-version":[{"id":66295,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/66292\/revisions\/66295"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/66294"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=66292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=66292"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=66292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}