{"id":59586,"date":"2022-10-30T19:38:14","date_gmt":"2022-10-30T19:38:14","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=59586"},"modified":"2022-10-30T19:38:14","modified_gmt":"2022-10-30T19:38:14","slug":"aplicaran-un-millon-de-vacunas-contra-la-influenza-en-tamaulipas","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/aplicaran-un-millon-de-vacunas-contra-la-influenza-en-tamaulipas\/","title":{"rendered":"Aplicar\u00e1n un mill\u00f3n de vacunas contra la influenza en Tamaulipas"},"content":{"rendered":"\n<p><em>Ciudad Victoria, Tamps.<\/em>&nbsp;La Secretar\u00eda de Salud aplicar\u00e1 un mill\u00f3n de dosis durante la campa\u00f1a de vacunaci\u00f3n contra la influenza estacional 2022-2023, dirigida a menores de 5 a 6 a\u00f1os de edad, as\u00ed como a los adultos mayores de 60 a\u00f1os, lo mismo que a mujeres embarazadas, pacientes con enfermedades cr\u00f3nicas y personal m\u00e9dico.<\/p>\n\n\n\n<p>Vicente Joel Hern\u00e1ndez Navarro, secretario de Salud de Tamaulipas, dijo que por instrucciones del gobernador morenista Am\u00e9rico Villarreal Anaya, la estrategia intensiva de vacunaci\u00f3n est\u00e1 dirigida principalmente al 95 por ciento de la poblaci\u00f3n m\u00e1s fr\u00e1gil, por la llegada de los primeros frentes fr\u00edo de la temporada invernal y que incrementa de la propagaci\u00f3n de virus que causan la influenza y el Covid-19.<\/p>\n\n\n\n<p>Hizo un llamado a proteger a la poblaci\u00f3n vulnerables y atender las recomendaciones difundidas de lavarse las manos frecuentemente, consumir frutas, verduras, l\u00edquidos en abundancia y evitar la dispersi\u00f3n del virus.<\/p>\n\n\n\n<p>La influenza afecta las v\u00edas respiratorias superiores, as\u00ed como afectar pulmones y bronquiolos, con s\u00edntomas de fiebre, dolor de anginas y garganta, tos, dolor de cabeza, dolores musculares que ameriten reposo y evitar fallecimientos.<\/p>\n\n\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- Composite Start -->\n<\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>","protected":false},"excerpt":{"rendered":"<p>Ciudad Victoria, Tamps.&nbsp;La Secretar\u00eda de Salud aplicar\u00e1 un mill\u00f3n de dosis durante la campa\u00f1a de vacunaci\u00f3n contra la influenza estacional 2022-2023, dirigida a menores de 5 a 6 a\u00f1os de edad, as\u00ed como a los adultos mayores de 60 a\u00f1os, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":59588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[59],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/59586"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=59586"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/59586\/revisions"}],"predecessor-version":[{"id":59589,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/59586\/revisions\/59589"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/59588"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=59586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=59586"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=59586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}