{"id":59574,"date":"2022-10-30T19:25:53","date_gmt":"2022-10-30T19:25:53","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=59574"},"modified":"2022-10-30T19:25:54","modified_gmt":"2022-10-30T19:25:54","slug":"esta-es-la-casa-que-compartian-ricky-martin-y-eduardo-verastegui-como-nidito-de-amor%ef%bf%bc","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/esta-es-la-casa-que-compartian-ricky-martin-y-eduardo-verastegui-como-nidito-de-amor%ef%bf%bc\/","title":{"rendered":"Esta es la casa que compart\u00edan Ricky Martin y Eduardo Ver\u00e1stegui como \u201cnidito de amor\u201d\ufffc"},"content":{"rendered":"\n<p>M\u00c9XICO.- Todo parece indicar que si hay un lugar en el que Ricky Martin y Eduardo Ver\u00e1stegui vivieron un intenso romance, fue en la antigua residencia del cantante puertorrique\u00f1o, ubicada en Miami Beach y construida en el a\u00f1o de 1937.<\/p>\n\n\n\n<p>As\u00ed lo dej\u00f3 ver el comunicador argentino Javier Ceriani, quien visit\u00f3 esta mansi\u00f3n en la que el cantante de \u201cLivin\u2019 la Vida Loca\u201d recibi\u00f3 a Ver\u00e1stegui y habr\u00edan vivido momentos llenos de pasi\u00f3n.<\/p>\n\n\n\n<p>Durante su recorrido, el periodista revel\u00f3 detalles de los espacios en los que pasaron cosas entre Ricky y el actor tales como la rec\u00e1mara principal e incluso la cocina.<\/p>\n\n\n\n<p>En otro video, se puede apreciar la residencia de arquitectura mediterr\u00e1nea, con una gran piscina y una enorme sala blanca, una figura de buda, y una tierna habitaci\u00f3n ambientada para sus hijos.<\/p>\n\n\n\n<p>La incre\u00edble morada contaba tambi\u00e9n con un \u00e1rea de recreaci\u00f3n para sus hijos con todo tipo de juguetes, aunque originalmente fue pensado como una sala de bar.<\/p>\n\n\n\n<p>Adem\u00e1s,ten\u00eda un estudio de m\u00fasica, el cual le permit\u00eda ofrecerle una mejor calidad de vida a sus dos primeros Matteo y Valentino, que tuvo a trav\u00e9s de la gestaci\u00f3n subrogada. Cabe se\u00f1alar que esta casa fue vendida en 2005 por el esposo de Jwan Yosef en 10.6 millones de d\u00f3lares.<\/p>\n\n\n\n<p>La exresidencia de Ricky Martin es de dos pisos y tiene una extensi\u00f3n de m\u00e1s de ocho mil pies cuadrados, seis rec\u00e1maras y seis ba\u00f1os, una cochera para dos veh\u00edculos, terraza, grandes \u00e1reas verdes, espacios para hu\u00e9spedes, spa, fuentes y por si fuera poco, un muelle que da a la Bah\u00eda de Biscayne.<\/p>\n\n\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- Composite Start -->\n<\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>","protected":false},"excerpt":{"rendered":"<p>M\u00c9XICO.- Todo parece indicar que si hay un lugar en el que Ricky Martin y Eduardo Ver\u00e1stegui vivieron un intenso romance, fue en la antigua residencia del cantante puertorrique\u00f1o, ubicada en Miami Beach y construida en el a\u00f1o de 1937. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":59576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[66],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/59574"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=59574"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/59574\/revisions"}],"predecessor-version":[{"id":59577,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/59574\/revisions\/59577"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/59576"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=59574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=59574"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=59574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}