{"id":58608,"date":"2022-10-12T00:45:55","date_gmt":"2022-10-12T00:45:55","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=58608"},"modified":"2022-10-12T00:45:56","modified_gmt":"2022-10-12T00:45:56","slug":"abuelita-se-infarta-en-fiesta-sorpresa-con-strippers-en-el-asilo%ef%bf%bc","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/abuelita-se-infarta-en-fiesta-sorpresa-con-strippers-en-el-asilo%ef%bf%bc\/","title":{"rendered":"Abuelita se infarta en fiesta sorpresa con strippers en el asilo\ufffc"},"content":{"rendered":"\n<p>Una\u00a0adulta mayor\u00a0sufri\u00f3 un\u00a0paro cardiaco\u00a0durante una\u00a0fiesta sorpresa\u00a0con\u00a0strippers\u00a0inclu\u00eddos,\u00a0que la influencer colombiana\u00a0Nadia Cartagena\u00a0organiz\u00f3 en un\u00a0asilo de ancianos\u00a0en\u00a0Colombia.<\/p>\n\n\n\n<p> El festejo y el accidente qued\u00f3 grabado en video y fue compartido en la cuenta de Instagram de la creadora de contenido que al momento contabiliza m\u00e1s de 48 mil reproducciones.<\/p>\n\n\n\n<p>El extra\u00f1o momento comenz\u00f3 con una stripper bailando con poca ropa quien baila twerk para uno de los residentes del asilo. Conforme el clip avanza, se observa a&nbsp;varios<\/p>\n\n\n\n<p>Strippers&nbsp;tanto&nbsp;mujeres&nbsp;como&nbsp;hombres&nbsp;acudir a distintos puntos dentro del recinto que fue identificado como la&nbsp;Fundaci\u00f3n Una Mano Amiga&nbsp;ubicado en El Prado, en la ciudad colombiana de Cartagena.<\/p>\n\n\n\n<p>Adem\u00e1s de dar vuelta en el asilo, los bailarines er\u00f3ticos comenzaron a&nbsp;dar de comer a los adultos mayores&nbsp;residentes, algunos alimentos como pasteles, ten\u00eda forma de genitales y los ofrec\u00edan a los ancianos.<\/p>\n\n\n\n<p>Durante el paseo de los strippers, de pronto varios de ellos, hombres,&nbsp;rodearon a una adulta mayor&nbsp;ataviada con un vestido azul y una diadema color rosa con orejas, quien de pronto se llev\u00f3&nbsp;ambas manos sobre su pecho&nbsp;y paulatinamente empez\u00f3 a&nbsp;caer al suelo.<\/p>\n\n\n\n<p>Varios strippers fueron bailar a un asilo de ancianos. Foto- IG<\/p>\n\n\n\n<p>Al ver la situaci\u00f3n, los hombres semidesnudos tratan de auxiliar a la mujer provecta mientras tiene&nbsp;espasmos&nbsp;en el suelo. Las personas que ayudan a la abuelita la instan a que&nbsp;tome agua&nbsp;para refrescarla antes de que llegue una&nbsp;ambulancia&nbsp;para ser asistida por personal m\u00e9dico.<\/p>\n\n\n\n<p>Con la ayuda de algunas de las bailarinas, la abuela fue asistida adem\u00e1s por los param\u00e9dicos quienes con la ayuda de los strippers, pudieron subir a una camilla a la mujer que se ve\u00eda&nbsp;a punto de desmayarse, de acuerdo con lo expuesto en el video compartido el pasado 27 de septiembre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tunden a Nadia Cartagena en las redes<\/h3>\n\n\n\n<p>Tras el incidente, Nadia Cartagena decidi\u00f3 subir el contenido en sus redes sociales a pesar de haber pasado por un&nbsp;terrible momento&nbsp;en&nbsp;su vida, tal como lo escribi\u00f3 en sus cuentas:<\/p>\n\n\n\n<p>\u201cHoy hice una fiesta er\u00f3tica o de adultos mayores, y me llev\u00e9 el&nbsp;susto m\u00e1s grande&nbsp;de mi vida porque no esperaba que pasara lo que pas\u00f3, y la verdad que&nbsp;lo siento mucho, solo Quer\u00eda&nbsp;darles&nbsp;un poco de&nbsp;diversi\u00f3n&nbsp;y no esperaba esa situaci\u00f3n, as\u00ed que quiero que comenten sobre la situaci\u00f3n\u201d, dijo la influencer.<\/p>\n\n\n\n<p>Los usuarios de Instagram arremetieron en contra de la influencer: \u201cAy no la verdad te ten\u00eda en otro concepto hay cosas que de veras&nbsp;no se deben publicar. Me parece una&nbsp;falta de respeto&nbsp;para estos ancianos,&nbsp;lo tuyo es ayudar al pr\u00f3jimo&nbsp;y con esto&nbsp;quedas salida de tono\u201d.<\/p>\n\n\n\n<p>Aunque tambi\u00e9n hubo otros m\u00e1s que afirmaron que se trat\u00f3 de un montaje, ya que vieron que en el clip hab\u00eda adultos mayores sonriendo ante la situaci\u00f3n. \u201cYo opino que&nbsp;es una actuaci\u00f3n, esa \u2018anciana\u2019 tiene las canas pintadas y est\u00e1 maquillada adem\u00e1s las personas mayores est\u00e1n&nbsp;ri\u00e9ndose\u201d, dijo un usuario.<\/p>\n\n\n\n<p>En respuesta a los comentarios, Nadia Cartagena asegur\u00f3 para el medio local El Universal, que el event\u00f3 lo organiz\u00f3 para crear&nbsp;conciencia&nbsp;sobre la &#8220;pobreza&#8221;&nbsp;y el &#8220;abandono&#8221;&nbsp;que&nbsp;sufren&nbsp;los&nbsp;adultos mayores, por lo cual les hizo una fiesta sorpresa. \u201cEl prop\u00f3sito del video es llamar a que se vea este problema y hacer un llamado a las autoridades distritales para que vigilen a esta gente\u201d.<\/p>\n\n\n\n<p>Agreg\u00f3 que obtuvo todos los permisos tanto para llevar a los strippers como para grabar el momento que qued\u00f3 documentado en su cuenta de Instagram.<\/p>\n\n\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- Composite Start -->\n<\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>","protected":false},"excerpt":{"rendered":"<p>Una\u00a0adulta mayor\u00a0sufri\u00f3 un\u00a0paro cardiaco\u00a0durante una\u00a0fiesta sorpresa\u00a0con\u00a0strippers\u00a0inclu\u00eddos,\u00a0que la influencer colombiana\u00a0Nadia Cartagena\u00a0organiz\u00f3 en un\u00a0asilo de ancianos\u00a0en\u00a0Colombia. El festejo y el accidente qued\u00f3 grabado en video y fue compartido en la cuenta de Instagram de la creadora de contenido que al momento contabiliza [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":58610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/58608"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=58608"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/58608\/revisions"}],"predecessor-version":[{"id":58611,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/58608\/revisions\/58611"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/58610"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=58608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=58608"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=58608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}