{"id":51072,"date":"2022-06-14T16:09:45","date_gmt":"2022-06-14T16:09:45","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=51072"},"modified":"2022-06-14T16:09:45","modified_gmt":"2022-06-14T16:09:45","slug":"estalla-pleito-por-el-control-del-congreso%ef%bf%bc","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/estalla-pleito-por-el-control-del-congreso%ef%bf%bc\/","title":{"rendered":"Estalla pleito por el control del Congreso\ufffc"},"content":{"rendered":"\n<p>TAMAULIPAS.- Diputados y simpatizantes de Morena irrumpieron en el Sal\u00f3n Legislativo para suspender la sesi\u00f3n y detener una iniciativa presentada por la bancada del PAN para modificar la Ley del Congreso y as\u00ed impedir que se pueda cambiar de nuevo la presidencia de la Junta de Coordinaci\u00f3n Pol\u00edtica.<\/p>\n\n\n\n<p>A pesar de este zafarrancho, por la tarde, la Comisi\u00f3n de Estudios Legislativos dio entrada a la iniciativa del PAN y la aprob\u00f3 para que sea votada hoy mismo en la sesi\u00f3n convocada para las 14:30 horas.<\/p>\n\n\n\n<p>Originalmente, los legisladores morenistas hab\u00edan abandonado el sal\u00f3n para evitar el qu\u00f3rum, sin embargo, la permanencia de la diputada Leticia Vargas (en ese momento todav\u00eda integrante de su bancada) permiti\u00f3 que la sesi\u00f3n se llevara a cabo.<\/p>\n\n\n\n<p>Justo cuando el diputado Ra\u00fal P\u00e9rez Lu\u00e9vano subi\u00f3 a Tribuna para leer el documento, volvieron al inmueble los diputados de Morena quienes tomaron la tribuna, al mismo tiempo que simpatizantes que se encontraban en las gradas rompieron el cerco de seguridad y lograron entrar al sal\u00f3n.<\/p>\n\n\n\n<p>La sesi\u00f3n del Congreso del Estado, que estaba programada para las 9:00 de la ma\u00f1ana, dio comienzo a las 10:24, luego de que el secretario de la mesa directiva, Carlos Fern\u00e1ndez, notific\u00f3 que hab\u00eda 19 diputados presentes y por tanto hab\u00eda mayor\u00eda.<\/p>\n\n\n\n<p>En galer\u00edas, la gente, que hab\u00eda llegado desde temprano, se hab\u00eda colocado en las gradas y comenzaron a gritar que fuera suspendida, adem\u00e1s de consignas en apoyo a L\u00f3pez Obrador, y en contra del PAN, \u201ces un honor estar con Obrador\u201d, \u201cya se van, ya se van\u201d y \u201cvendida\u201d, refiri\u00e9ndose a Leticia Vargas de Morena y Nancy Ru\u00edz, quien hace meses se declar\u00f3 sin partido.<\/p>\n\n\n\n<p>Apenas hab\u00edan transcurrido 15 minutos, el diputado del PAN, Ra\u00fal P\u00e9rez Lu\u00e9vano daba lectura a la iniciativa para modificar la Ley interna del Congreso, cuando de manera intempestiva, llegaron los diputados de Morena y tomaron la tribuna, arrebatando micr\u00f3fonos y papeles de la mesa directiva.<\/p>\n\n\n\n<p>El primero en entrar fue Alberto Granados con meg\u00e1fono en mano y detr\u00e1s de \u00e9l la diputada Magaly Deandar, Humberto Prieto, invitando a los asistentes en galer\u00edas a bajar y entrar al pleno, lo que logr\u00f3 un nutrido grupo de personas.<\/p>\n\n\n\n<p>Eliphaleth G\u00f3mez Lozano, diputado de Valle Hermoso, explic\u00f3 que primero se hab\u00edan retirado antes de iniciar la sesi\u00f3n, pues pensaban que no habr\u00eda quorum para llevarla a cabo.<\/p>\n\n\n\n<p>\u201cTodo indicaba que no iba a haber quorum, porque hab\u00eda metido la diputada Leticia, un justificante por salud, tomamos la mejor decisi\u00f3n en ese momento, sin embargo, vimos que ellos estaban tomando otras acciones para dar el madruguete\u201d.<\/p>\n\n\n\n<p>La iniciativa de Acci\u00f3n Nacional, propone modificar el art\u00edculo 29 p\u00e1rrafo segundo.<\/p>\n\n\n\n<p>\u201cSer\u00e1 presidenta (e) de la Junta durante la legislatura, la o el diputado que mediante votaci\u00f3n directa sea elegido democr\u00e1ticamente y obtenga la votaci\u00f3n de las dos terceras partes de los integrantes del Congreso\u201d.<\/p>\n\n\n\n<p>Apenas el pasado 1 de junio, fue publicado en el Peri\u00f3dico Oficial del Estado, el decreto No. 65-146 que reform\u00f3 los p\u00e1rrafos primero y segundo del art\u00edculo 29 de la ley Sobre la organizaci\u00f3n y funcionamiento internos del Congreso, aprobado el 9 de marzo de este a\u00f1o.<\/p>\n\n\n\n<p>Mismo que establec\u00eda que ser\u00e1 presidenta (e) de Junta durante la Legislatura, la o el diputado que mediante votaci\u00f3n directa sea elegido democr\u00e1ticamente y obtenga la mayor\u00eda relativa de los integrantes del Congreso.<\/p>\n\n\n\n<p>Con esa reforma, el PAN y el PRI hab\u00edan logrado destituir del cargo de presidente de la Jucopo a Armando Zertuche Zuani, luego que Morena hab\u00eda modificado tambi\u00e9n el 4 de noviembre del 2021, el p\u00e1rrafo 2 del art\u00edculo 29.<\/p>\n\n\n\n<p>Estableciendo que ser\u00eda presidente de la Junta por la duraci\u00f3n de la Legislatura, el coordinador del grupo parlamentario del partido pol\u00edtico que haya obtenido m\u00e1s votos en el estado, en la elecci\u00f3n correspondiente a la Legislatura en turno.<\/p>\n\n\n\n<p>\u201cNo se los vamos a permitir, ellos hicieron al inicio un movimiento a su favor y hoy quieren cambiarlo, tienen que ser congruentes con lo que piensan, con lo que hacen y con lo que dicen\u201d, dijo Casandra de los Santos Flores.<\/p>\n\n\n\n<p>Para tratar de impedir que la iniciativa fuera presentada, la diputada \u00darsula Salazar tom\u00f3 uno de los micr\u00f3fonos que usaba el panista Ra\u00fal P\u00e9rez, mientras que el otro fue tomado por Alberto Granados, quien de pronto se enfrent\u00f3 a Leticia S\u00e1nchez con quien se gritone\u00f3 y jalone\u00f3.<br>En la mesa directiva, la batalla era igual de intensa, insultos, amenazas, manotazos entre unos y otros, mientras desde galer\u00edas y dentro del pleno, los asistentes segu\u00edan gritando, impidiendo que la sesi\u00f3n se llevara a cabo en orden.<br>El presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica, F\u00e9lix Fernando Garc\u00eda Aguiar, trat\u00f3 de hablar con \u00darsula Salazar, coordinadora de los morenistas, sin llegar a un acuerdo, luego se vio tratando de hacer lo mismo con Armando Zertuche, con los mismos resultados.<\/p>\n\n\n\n<p>F\u00e9lix Fernando Garc\u00eda Aguiar, llam\u00f3 al 911, se\u00f1alando que se hab\u00edan presentado actos de vandalismo, por lo que m\u00e1s tarde llegaron elementos de la Polic\u00eda Estatal en tres patrullas.<\/p>\n\n\n\n<p>Los encargados de seguridad del Congreso, les se\u00f1alaron que todo estaba ya en orden, el encargado de la seguridad interna del recinto legislativo, les pidi\u00f3 se retiraran y solo mantuvieran rondines en el per\u00edmetro del Congreso.<\/p>\n\n\n\n<p>El presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica, conden\u00f3 lo sucedido, \u201ctel\u00e9fonos, micr\u00f3fonos da\u00f1ados, las instalaciones del pleno, eso no se puede permitir, reconocemos la libertad de expresi\u00f3n en todas sus formas, siempre y cuando sea con respeto y no se llegue a la agresiones ni se incite a la gente a generar desorden al pleno\u201d.<\/p>\n\n\n\n<p>El diputado Armando Zertuche, por su parte, dijo que hasta ahora, el PAN, ha estado \u201csuplantando, malinterpretando a conveniencia, estas situaciones de la ley interna, a cada santo le llega su hora y con la acci\u00f3n del d\u00eda de hoy, vemos abierta y claramente, una intenci\u00f3n de volver a blindar al gobernador\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que para la sesi\u00f3n no se hab\u00eda convocado a los integrantes de la Junta de Coordinaci\u00f3n Pol\u00edtica de los partidos pol\u00edticos, para notificar sobre la agenda del d\u00eda, \u201cpor eso asumimos que lo que podr\u00edan haber presentado no era correcto, lo que hicimos fue parar una acci\u00f3n que a todas luces, mostraba irregularidades\u201d.<\/p>\n\n\n\n<p>Cuando parec\u00eda que la calma hab\u00eda vuelto al Palacio Legislativo, de manera sorpresiva, la Comisi\u00f3n de Estudios Legislativos convoc\u00f3 a sesi\u00f3n lo que tom\u00f3 por sorpresa a los diputados de Morena. Cuando llegaron a la sala, ya se estaba presentando la iniciativa para ser dictaminada.<\/p>\n\n\n\n<p>A pesar de que los legisladores morenistas trataron de impedirlo, la mayor\u00eda del PAN logr\u00f3 su aprobaci\u00f3n, por lo que se estima que hoy se presente ante el Pleno el dictamen que adem\u00e1s plantea que para cualquier nueva modificaci\u00f3n a la Ley Interna del Congreso se requiera de la votaci\u00f3n de dos terceras partes de los diputados.<\/p>\n\n\n\n<p>Es decir, esto impedir\u00eda por completo a los morenistas una nueva modificaci\u00f3n que les permita retomar el control de la Junta de Coordinaci\u00f3n Pol\u00edtica.<\/p>\n\n\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- Composite Start -->\n<\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>","protected":false},"excerpt":{"rendered":"<p>TAMAULIPAS.- Diputados y simpatizantes de Morena irrumpieron en el Sal\u00f3n Legislativo para suspender la sesi\u00f3n y detener una iniciativa presentada por la bancada del PAN para modificar la Ley del Congreso y as\u00ed impedir que se pueda cambiar de nuevo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":51074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[59],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/51072"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=51072"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/51072\/revisions"}],"predecessor-version":[{"id":51075,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/51072\/revisions\/51075"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/51074"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=51072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=51072"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=51072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}