{"id":46040,"date":"2022-04-09T02:05:42","date_gmt":"2022-04-09T02:05:42","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=46040"},"modified":"2022-04-09T02:05:43","modified_gmt":"2022-04-09T02:05:43","slug":"nos-jugamos-el-futuro-en-esta-eleccion-americo","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/nos-jugamos-el-futuro-en-esta-eleccion-americo\/","title":{"rendered":"Nos jugamos el futuro en esta elecci\u00f3n: Am\u00e9rico"},"content":{"rendered":"\n<p>R\u00edo Bravo, Tam.- \u201cNos estamos jugando el futuro de nuestra sociedad, entre el bienestar para todos y la continuidad de gobiernos corruptos y desaseados\u201d, afirm\u00f3 el doctor Am\u00e9rico Villarreal Anaya, candidato com\u00fan de Morena-Verde-PT a la gubernatura del Estado.<\/p>\n\n\n\n<p><br>Acompa\u00f1ado por diputados federales y locales y cientos de riobravenses congregados en la colonia Manuel Cavazos Lerma, el candidato morenista hizo una radiograf\u00eda de c\u00f3mo ser\u00e1 su gobierno y el perfil de quienes colaboren con \u00e9l.<br><\/p>\n\n\n\n<p>Ante cientos de riobravenses que se comprometieron a hacer campa\u00f1a casa por casa para ganar la gubernatura, el doctor Am\u00e9rico, ofreci\u00f3 cuidar el agua para un mejor desarrollo y calidad de vida de toda la poblaci\u00f3n tamaulipeca.<\/p>\n\n\n\n<p><br>Am\u00e9rico Villarreal Anaya destac\u00f3 que su gabinete estar\u00e1 integrado por tamaulipecos y tamaulipecas capaces de tomar las decisiones m\u00e1s acertadas que impulsen el bienestar de nuestros ni\u00f1os y ni\u00f1as y el futuro de Tamaulipas.<\/p>\n\n\n\n<p><br>Ser\u00e1n servidores p\u00fablicos que den resultados, honestos, con una probada capacidad y que tengan adem\u00e1s un profundo amor por Tamaulipas.<\/p>\n\n\n\n<p><br>El candidato hizo un llamado a los votantes para que elijan bien el pr\u00f3ximo 5 de junio: \u201cla opci\u00f3n est\u00e1 entre decidir por una transformaci\u00f3n que traiga el bienestar y servicios para todos y la continuidad que representa al actual gobierno que ha sido omiso y corrupto&#8221;.<\/p>\n\n\n\n<p><br>\u201cEst\u00e1 en juego el futuro de la sociedad tamaulipeca; por eso hay que decidir bien este 5 de junio\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p><br>Por su parte Jes\u00fas De Le\u00f3n G\u00f3mez, el l\u00edder de la colonia &#8220;Manuel Cavazos Lerma&#8221;, se comprometi\u00f3 ante el candidato de \u201cJuntos Hacemos Historia\u201d, a iniciar una campa\u00f1a casa por casa para que todo R\u00edo Bravo vote por Morena.<\/p>\n\n\n\n<p><br>El legislador federal, Tom\u00e1s Gloria Requena dijo &#8220;Somos la Alianza invencible que llevar\u00e1 al doctor a la gubernatura del estado&#8221;.<br>Requena apunt\u00f3 que &#8220;Tamaulipas est\u00e1 a punto de morir, pero El Doctor lo va a revivir&#8221;.<\/p>\n\n\n\n<p><br>El doctor Am\u00e9rico Villarreal, estuvo acompa\u00f1ado de su esposa Mar\u00eda de Villarreal, adem\u00e1s de l\u00edderes de colonias y cientos de personas que se volcaron a abrazarlo y decirle que est\u00e1n con \u00e9l porque es un hombre honesto que trabajar\u00e1 por los m\u00e1s necesitados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00edo Bravo, Tam.- \u201cNos estamos jugando el futuro de nuestra sociedad, entre el bienestar para todos y la continuidad de gobiernos corruptos y desaseados\u201d, afirm\u00f3 el doctor Am\u00e9rico Villarreal Anaya, candidato com\u00fan de Morena-Verde-PT a la gubernatura del Estado. Acompa\u00f1ado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":46042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[59],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/46040"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=46040"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/46040\/revisions"}],"predecessor-version":[{"id":46043,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/46040\/revisions\/46043"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/46042"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=46040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=46040"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=46040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}