{"id":46027,"date":"2022-04-08T18:55:57","date_gmt":"2022-04-08T18:55:57","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=46027"},"modified":"2022-04-08T18:56:09","modified_gmt":"2022-04-08T18:56:09","slug":"aun-no-inician-las-vacaciones-y-aumentaron-los-casos-de-covid-en-matamoros","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/aun-no-inician-las-vacaciones-y-aumentaron-los-casos-de-covid-en-matamoros\/","title":{"rendered":"A\u00fan no inician las vacaciones y aumentaron los casos de Covid en Matamoros"},"content":{"rendered":"\n<p>Matamoros, Tamaulipas.- Apenas iniciar\u00e1 el periodo vacacional de Semana Santa y los casos positivos de Covid-19 van en aumento de nueva cuenta en Matamoros, al grado que ayer jueves ya se alcanzaron los 121 casos positivos, cifra que ya hab\u00eda disminuido, indic\u00f3 el secretario de Salud, Jaime Avalos Guti\u00e9rrez. <\/p>\n\n\n\n<p>Destac\u00f3 que sin ser vacaciones ya hab\u00eda un aumento en los casos positivos de esta enfermedad, pero ahora con estos d\u00edas de asueto se estar\u00eda presentando un nuevo repunte y la ciudad pudiera cambiar de sem\u00e1foro epidemiol\u00f3gico naranja a rojo. <\/p>\n\n\n\n<p>Manifest\u00f3 que este nuevo repunte que se est\u00e1 presentando en la ciudad es a consecuencia de que la comunidad no est\u00e1 siguiendo las recomendaciones emitidas por las autoridades de salud, por lo que insisti\u00f3 que se requiere seguir tomando en cuenta cada una de las medidas preventivas que se han generado para evitar el contagio. <\/p>\n\n\n\n<p>Record\u00f3 que fue autorizado el uso de cubrebocas opcional en espacios al aire libre, pero la mejor decisi\u00f3n de las personas es seguirse protegiendo, solo de esta manera evitar\u00e1n contagiarse de esta enfermedad.<\/p>\n\n\n\n<p> Avalos Guti\u00e9rrez no descart\u00f3 que una vez que se regrese de vacaciones Matamoros vuelva al sem\u00e1foro rojo, considerando la movilidad de personas que se espera para estos pr\u00f3ximos d\u00edas. Precis\u00f3 que en esta semana que concluye los casos han ido aumentando, ya se hab\u00eda llegado a los 100 o menos activos, pero desgraciadamente vuelve a<\/p>\n\n\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- Composite Start -->\n<\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>","protected":false},"excerpt":{"rendered":"<p>Matamoros, Tamaulipas.- Apenas iniciar\u00e1 el periodo vacacional de Semana Santa y los casos positivos de Covid-19 van en aumento de nueva cuenta en Matamoros, al grado que ayer jueves ya se alcanzaron los 121 casos positivos, cifra que ya hab\u00eda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":46029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[59],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/46027"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=46027"}],"version-history":[{"count":2,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/46027\/revisions"}],"predecessor-version":[{"id":46031,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/46027\/revisions\/46031"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/46029"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=46027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=46027"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=46027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}