{"id":29983,"date":"2021-09-05T14:59:34","date_gmt":"2021-09-05T14:59:34","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=29983"},"modified":"2021-09-05T14:59:34","modified_gmt":"2021-09-05T14:59:34","slug":"julio-urias-consigue-su-triunfo-16-y-los-dodgers-son-lideres-en-el-oeste","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/julio-urias-consigue-su-triunfo-16-y-los-dodgers-son-lideres-en-el-oeste\/","title":{"rendered":"Julio Ur\u00edas consigue su triunfo 16 y los Dodgers son lideres en el Oeste"},"content":{"rendered":"\n<p>Redacci\u00f3n <br><strong> Noticias Telered<\/strong><\/p>\n\n\n\n<p>Julio Ur\u00edas consigui\u00f3 su&nbsp;d\u00e9cima sexta victoria de la temporada, al conducir a Los Angeles Dodgers al triunfo 6-1 sobre San Francisco Giants en el Oracle Park,&nbsp;en un juego por el&nbsp;liderato del Oeste de la Liga Nacional,&nbsp;en el que ya se encuentran empatados con marca de 86-50.<\/p>\n\n\n\n<p>El equipo angelino le dio la pelota al lanzador mexicano y&nbsp;\u00e9ste tuvo una actuaci\u00f3n destacada desde la lomita, al lanzar cinco entradas y dos tercios,&nbsp;con ocho ponches, ocho hits y una carrera limpia.<\/p>\n\n\n\n<p>A su salida,&nbsp;el zurdo dej\u00f3 el partido ganado 3-1, con una ventaja que tomaron desde la primera entrada&nbsp;para despu\u00e9s comenzar a colgar ceros en la pizarra hasta la sexta entrada en la que&nbsp;se pusieron 4-1 para redondear la victoria&nbsp;en la novena con dos carreras m\u00e1s.Este triunfo significa mucho para los Dodgers&nbsp;al instalarse en el liderato, as\u00ed como para el pitcher oriundo de Culiac\u00e1n, Sinaloa, quien es el primer lugar en triunfos de la MLB con 16,&nbsp;por encima de Kyle Hendricks de los Chicago Cubs.<\/p>\n\n\n\n<p>El productivo mes de agosto que tuvo Ur\u00edas con 1.38 de efectividad&nbsp;se est\u00e1 confirmando con esta nueva presentaci\u00f3n en la que se le vio s\u00f3lido, dejando su efectividad en 3.11.<\/p>\n\n\n<p><!-- Composite Start -->\n<\/p><div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n Noticias Telered Julio Ur\u00edas consigui\u00f3 su&nbsp;d\u00e9cima sexta victoria de la temporada, al conducir a Los Angeles Dodgers al triunfo 6-1 sobre San Francisco Giants en el Oracle Park,&nbsp;en un juego por el&nbsp;liderato del Oeste de la Liga Nacional,&nbsp;en el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/29983"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=29983"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/29983\/revisions"}],"predecessor-version":[{"id":29986,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/29983\/revisions\/29986"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/29985"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=29983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=29983"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=29983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}