{"id":14235,"date":"2020-12-07T14:38:48","date_gmt":"2020-12-07T14:38:48","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=14235"},"modified":"2020-12-07T14:38:52","modified_gmt":"2020-12-07T14:38:52","slug":"marcha-bien-temporada-de-caceria-2","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/marcha-bien-temporada-de-caceria-2\/","title":{"rendered":"Marcha bien temporada de cacer\u00eda"},"content":{"rendered":"<p>REdaccion<br \/>\nNoticias Telered<\/p>\n<p>Llegan mil cazadores y se espera una derrama de 10 millones de d\u00f3lares, estima la Coordinaci\u00f3n de Turismo Cineg\u00e9tico<\/p>\n<p>Con el cumplimiento de todas las medidas sanitarias por el Covid-19,  cerca de mil cazadores llegaron a la regi\u00f3n en esta temporada, por lo que se espera una derrama econ\u00f3mica de 10 millones de d\u00f3lares, se\u00f1al\u00f3 C\u00e9sar Johnson Villarreal, coordinador de Turismo Cineg\u00e9tico.<\/p>\n<p>De acuerdo a los registros del a\u00f1o 2019, para esta fecha arribaron poco m\u00e1s de mil 300 cazadores, inform\u00f3 el coordinador y se dej\u00f3 una derrama econ\u00f3mica de 12 millones de d\u00f3lares al final de la temporada.<\/p>\n<p>\u201cVamos bien, de acuerdo a lo esperado por la situaci\u00f3n delicada que se vive en el pa\u00eds con la pandemia, por lo que estamos un 25-30 por ciento abajo en el n\u00famero de cazadores que llegaron a la regi\u00f3n, en comparaci\u00f3n con el a\u00f1o pasado\u201d, se\u00f1al\u00f3.<\/p>\n<p>Refiri\u00f3 que aunque es una actividad deportiva al aire libre, muchos cazadores optaron por no salir esta temporada de caza para prevenir y cuidarse de un posible contagio de Covid-19.<\/p>\n<p>\u201cAqu\u00ed las autoridades est\u00e1n muy estrictas en el cuidado de la gente, y los cazadores que nos visitan lo hacen con todas las medidas de seguridad y salud, por lo que arriban grupos peque\u00f1os a los ranchos y esperamos que a mediados de diciembre lleguen m\u00e1s cazadores\u201d, indic\u00f3.<\/p>\n<p>C\u00e9sar Johnson coment\u00f3 que esos d\u00edas son el punto m\u00e1s alto que se tienen de visitas de cazadores porque hay m\u00e1s movimiento de venados y obtienen muy buenos trofeos.<\/p>\n<p>En esta temporada solo participaron 550 de los 800 ranchos que usualmente reciben a los grupos de cazadores.<\/p>\n<p>Por \u00faltimo, exhort\u00f3 a las y los neolaredenses a ser buenos anfitriones de los cazadores, pues la derrama econ\u00f3mica que dejan en la ciudad es muy buena para la reactivaci\u00f3n del mercado interno, en beneficio de las familias neolaredenses.<\/p>\n<p><!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REdaccion Noticias Telered Llegan mil cazadores y se espera una derrama de 10 millones de d\u00f3lares, estima la Coordinaci\u00f3n de Turismo Cineg\u00e9tico Con el cumplimiento de todas las medidas sanitarias por el Covid-19, cerca de mil cazadores llegaron a la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":14230,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/14235"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=14235"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/14235\/revisions"}],"predecessor-version":[{"id":14237,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/14235\/revisions\/14237"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/14230"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=14235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=14235"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=14235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}