{"id":114336,"date":"2026-07-15T07:08:43","date_gmt":"2026-07-15T07:08:43","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=114336"},"modified":"2026-07-15T07:08:45","modified_gmt":"2026-07-15T07:08:45","slug":"empujan-reactivar-otra-regularizacion","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/empujan-reactivar-otra-regularizacion\/","title":{"rendered":"Empujan reactivar otra regularizaci\u00f3n"},"content":{"rendered":"<p>REYNOSA, TAMAULIPAS.- Con el prop\u00f3sito de regularizar los m\u00e1s de 230 mil veh\u00edculos de procedencia extranjera que quedaron fuera del programa federal en Reynosa, contin\u00faan las gestiones para reactivar el decreto de regularizaci\u00f3n en Tamaulipas bajo las mismas condiciones que el esquema anterior.<\/p>\n<p>El director general de Oficinas Fiscales del Estado, Marcelo Ol\u00e1n Mendoza, inform\u00f3 que el pasado 10 de julio sostuvo una reuni\u00f3n en la Ciudad de M\u00e9xico, por lo que existen amplias posibilidades de que la Federaci\u00f3n autorice una ampliaci\u00f3n del programa.<\/p>\n<p>Explic\u00f3 que las gestiones forman parte de la pol\u00edtica impulsada por el Gobierno del Estado para brindar certeza jur\u00eddica a los propietarios de veh\u00edculos extranjeros, en coordinaci\u00f3n con legisladores federales.<\/p>\n<p>Precis\u00f3 que la propuesta consiste en mantener las mismas reglas del decreto presidencial anterior, pero incluyendo a todas las unidades que no alcanzaron a regularizarse antes de que concluyera el programa.<\/p>\n<p>Indic\u00f3 que el n\u00famero de veh\u00edculos pendientes es considerable, particularmente en Reynosa, donde miles de propietarios quedaron fuera del beneficio y actualmente enfrentan elevados costos para nacionalizar sus unidades.<\/p>\n<p>Record\u00f3 que, durante la vigencia del decreto, la regularizaci\u00f3n ten\u00eda un costo de dos mil 500 pesos; sin embargo, actualmente nacionalizar un veh\u00edculo puede representar un gasto muy superior. Como ejemplo, mencion\u00f3 el caso de un autom\u00f3vil modelo 2010, cuyo tr\u00e1mite alcanz\u00f3 un costo cercano a los 60 mil pesos.<\/p>\n<p>Ol\u00e1n Mendoza estim\u00f3 que tan solo en la frontera de Tamaulipas existen alrededor de 230 mil veh\u00edculos pendientes de regularizaci\u00f3n, por lo que actualmente se realiza un padr\u00f3n para conocer el n\u00famero exacto de unidades que quedaron fuera del programa.<\/p>\n<p>Por otra parte, confirm\u00f3 que durante el periodo vacacional las Oficinas Fiscales permanecer\u00e1n abiertas mediante un sistema de guardias, por lo que no suspender\u00e1n actividades durante los d\u00edas h\u00e1biles, en cumplimiento de las instrucciones del gobernador.<\/p>\n<p>Se\u00f1al\u00f3 que el objetivo es facilitar que los contribuyentes aprovechen los est\u00edmulos fiscales vigentes, los cuales concluyen el pr\u00f3ximo 31 de julio.<\/p>\n<p>Entre los beneficios destacan un descuento del 30 por ciento para contribuyentes cumplidos. Adem\u00e1s, los propietarios de veh\u00edculos modelos 2002 a 2017 podr\u00e1n regularizar sus adeudos pagando \u00fanicamente cinco mil 990 pesos; para unidades modelo 2011 y anteriores, el costo ser\u00e1 de tres mil 990 pesos.<\/p>\n<p>Asimismo, la licencia de conducir econ\u00f3mica tiene un costo de mil 173 pesos, mientras que los motociclistas podr\u00e1n ponerse al corriente con 870 pesos y obtener su licencia por 800 pesos.<\/p>\n<p><!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n<p><!-- Composite End --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REYNOSA, TAMAULIPAS.- Con el prop\u00f3sito de regularizar los m\u00e1s de 230 mil veh\u00edculos de procedencia extranjera que quedaron fuera del programa federal en Reynosa, contin\u00faan las gestiones para reactivar el decreto de regularizaci\u00f3n en Tamaulipas bajo las mismas condiciones que [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":114339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[59],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/114336"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=114336"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/114336\/revisions"}],"predecessor-version":[{"id":114340,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/114336\/revisions\/114340"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/114339"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=114336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=114336"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=114336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}