{"id":108510,"date":"2024-12-06T03:33:12","date_gmt":"2024-12-06T03:33:12","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=108510"},"modified":"2024-12-06T03:33:13","modified_gmt":"2024-12-06T03:33:13","slug":"oms-investiga-enfermedad-desconocida-que-ha-matado-a-79-personas-en-el-congo","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/oms-investiga-enfermedad-desconocida-que-ha-matado-a-79-personas-en-el-congo\/","title":{"rendered":"OMS investiga \u2018enfermedad desconocida\u2019 que ha matado a 79 personas en el Congo"},"content":{"rendered":"<p>Ginebra. &#8211;  La Organizaci\u00f3n Mundial de la Salud (OMS) inform\u00f3 de que est\u00e1 investigando sobre el terreno la enfermedad &#8220;de origen a\u00fan desconocido&#8221; que al parecer ha causado 79 muertos en el oeste de la Rep\u00fablica Democr\u00e1tica del Congo (RDC).<\/p>\n<p>&#8220;Estamos trabajando con las autoridades nacionales para hacer un seguimiento las informaciones sobre la enfermedad desconocida con el fin de entender la situaci\u00f3n, y hemos enviado un equipo a la zona para recoger muestras para investigaciones de laboratorio&#8221;, indic\u00f3 a EFE el portavoz de la OMS Tarik Jasarevic.<\/p>\n<p>Los fallecimientos y otros casos no mortales (se habla de unos 376 afectados) han sido registrados desde el pasado 24 de octubre en la provincia de Kwango, fronteriza con Angola, seg\u00fan indicaron las autoridades sanitarias congole\u00f1as.<\/p>\n<p>Los s\u00edntomas de la enfermedad incluyen fiebre, dolores de cabeza, secreci\u00f3n nasal y tos, dificultad para respirar y anemia.<\/p>\n<p>La RDC sufre adem\u00e1s un brote de mpox (enfermedad antes conocida como viruela s\u00edmica) con m\u00e1s de 47 mil casos sospechosos y alrededor de un millar de muertes, lo que llev\u00f3 a la OMS a declarar una emergencia internacional por su avance, a\u00fan vigente, el pasado mes de agosto.<\/p>\n<p>\u00bfQu\u00e9 es el mpox?<br \/>\nEl mpox, tambi\u00e9n conocido como viruela s\u00edmica, es una enfermedad infecciosa causada por un virus que pertenece a la misma familia que la viruela.<\/p>\n<p>\u00bfC\u00f3mo se transmite?<br \/>\nContacto cercano: Principalmente a trav\u00e9s del contacto directo con las lesiones de una persona infectada, fluidos corporales, gotitas respiratorias durante una conversaci\u00f3n prolongada cara a cara o contacto sexual.<br \/>\nObjetos contaminados: Tambi\u00e9n puede transmitirse al tocar objetos, telas (ropa, ropa de cama) o superficies contaminadas con el virus.<br \/>\n\u00bfCu\u00e1les son los s\u00edntomas?<br \/>\nLos s\u00edntomas suelen aparecer entre 5 y 21 d\u00edas despu\u00e9s de la exposici\u00f3n al virus y pueden incluir:<\/p>\n<p>Fiebre<br \/>\nDolor de cabeza<br \/>\nDolor muscular<br \/>\nDolor de espalda<br \/>\nGanglios linf\u00e1ticos inflamados<br \/>\nFatiga<br \/>\nErupci\u00f3n cut\u00e1nea.<br \/>\n<!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ginebra. &#8211; La Organizaci\u00f3n Mundial de la Salud (OMS) inform\u00f3 de que est\u00e1 investigando sobre el terreno la enfermedad &#8220;de origen a\u00fan desconocido&#8221; que al parecer ha causado 79 muertos en el oeste de la Rep\u00fablica Democr\u00e1tica del Congo (RDC). [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":108513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[61],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/108510"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=108510"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/108510\/revisions"}],"predecessor-version":[{"id":108514,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/108510\/revisions\/108514"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/108513"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=108510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=108510"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=108510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}