{"id":108490,"date":"2024-12-06T03:23:48","date_gmt":"2024-12-06T03:23:48","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=108490"},"modified":"2024-12-06T03:23:49","modified_gmt":"2024-12-06T03:23:49","slug":"mueren-13-ninos-por-la-bacteria-klebsiella-oxytoca-en-el-estado-de-mexico","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/mueren-13-ninos-por-la-bacteria-klebsiella-oxytoca-en-el-estado-de-mexico\/","title":{"rendered":"Mueren 13 ni\u00f1os por la bacteria Klebsiella oxytoca en el Estado de M\u00e9xico"},"content":{"rendered":"<p>Ciudad de M\u00e9xico.- Al menos 13 ni\u00f1os murieron en el Estado de M\u00e9xico, posiblemente por la bacteria Klebsiella oxytoca, de la que se infectaron en hospitales de la entidad, la m\u00e1s poblada del pa\u00eds, inform\u00f3 este jueves la Secretar\u00eda de Salud (SSa) del Gobierno de M\u00e9xico.<\/p>\n<p>La dependencia federal estudi\u00f3 20 casos, de los que cuatro contin\u00faan como probables y uno descartado, en pacientes de 0 a 14 a\u00f1os por posible contaminaci\u00f3n de nutrici\u00f3n parenteral (NPT), es decir, alimentaci\u00f3n ultravenosa, en tres hospitales p\u00fablicos y una cl\u00ednica privada.<\/p>\n<p>&#8220;De los 20 casos, se registraron 13 defunciones de pacientes que pose\u00edan comorbilidades por lo que se encuentran en proceso de dictaminaci\u00f3n para determinar si la causa de muerte est\u00e1 asociada a la ITS (infecci\u00f3n) por Klebsiella oxytoca MDR. Asimismo, siete pacientes se encuentran hospitalizados&#8221;, detall\u00f3 en un comunicado.<\/p>\n<p>Esta bacteria provoca infecciones urinarias o de v\u00edas biliares, y suele reportarse en hospitales y, en especial, en pacientes diab\u00e9ticos, que han recibido antes antibi\u00f3ticos o con alguna enfermedad previa de gravedad.<\/p>\n<p>Las investigaciones iniciales del gobierno indican una posible contaminaci\u00f3n en las soluciones de NPT de la empresa SAFE, pero no se descartan otras hip\u00f3tesis, a\u00f1adi\u00f3 el texto informativo.<\/p>\n<p>Los an\u00e1lisis buscan identificar la fuente del brote y &#8220;se mantiene un monitoreo permanente para descartar posibles brotes en otras entidades&#8221;, asever\u00f3 la dependencia.<\/p>\n<p>Por el brote, la Comisi\u00f3n Federal para la Protecci\u00f3n contra Riesgos Sanitarios (Cofepris) emiti\u00f3 una alerta sanitaria para advertir a los profesionales de la salud y al Sector Salud &#8220;sobre la inmovilizaci\u00f3n de manera preventiva y suspensi\u00f3n del uso y administraci\u00f3n de soluciones intravenosas de nutrici\u00f3n parenteral&#8221;.<\/p>\n<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, asegur\u00f3 en su conferencia matutina de este jueves que el brote &#8220;est\u00e1 controlado&#8221;.<br \/>\n<!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico.- Al menos 13 ni\u00f1os murieron en el Estado de M\u00e9xico, posiblemente por la bacteria Klebsiella oxytoca, de la que se infectaron en hospitales de la entidad, la m\u00e1s poblada del pa\u00eds, inform\u00f3 este jueves la Secretar\u00eda de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":108493,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/108490"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=108490"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/108490\/revisions"}],"predecessor-version":[{"id":108494,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/108490\/revisions\/108494"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/108493"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=108490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=108490"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=108490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}