{"id":103552,"date":"2024-09-21T04:48:42","date_gmt":"2024-09-21T04:48:42","guid":{"rendered":"http:\/\/noticiastelered.com\/PortalDNoticias\/?p=103552"},"modified":"2024-09-21T04:48:43","modified_gmt":"2024-09-21T04:48:43","slug":"condenan-a-cadena-perpetua-a-una-menor-en-eu-por-asesinar-a-su-madre","status":"publish","type":"post","link":"http:\/\/noticiastelered.com\/PortalDNoticias\/condenan-a-cadena-perpetua-a-una-menor-en-eu-por-asesinar-a-su-madre\/","title":{"rendered":"Condenan a cadena perpetua a una menor en EU por asesinar a su madre"},"content":{"rendered":"<p>Miami.- Una menor de 15 a\u00f1os declarada culpable de asesinar a su madre a tiros con un rev\u00f3lver e intentar matar a su padrastro en marzo pasado en el estado de Mississippi, en el sur de EE.UU., fue condenada este viernes por un tribunal a cadena perpetua.<\/p>\n<p>Carly Madison Gregg fue sentenciada tambi\u00e9n a una condena de diez a\u00f1os por el delito de manipulaci\u00f3n de pruebas.<\/p>\n<p>Gregg ten\u00eda 14 a\u00f1os en el momento del asesinato de su madre, Ashley Smyle, de 40 a\u00f1os, e intent\u00f3 de asesinato de su padrastro de 39 a\u00f1os, Heath Smylie, el 19 de marzo pasado en la casa de la familia en la localidad de Brandon (Mississippi).<\/p>\n<p>Antes de que se leyera la sentencia, la fiscal pidi\u00f3 al jurado que condenara a Gregg a cadena perpetua sin libertad condicional, con el argumento de que la menor no hab\u00eda mostrado ning\u00fan tipo de remordimiento por el crimen cometido y que no ten\u00eda serios problemas de salud mental, recogi\u00f3 el diario local Hattiesburg American.<\/p>\n<p>La defensa de Gregg hab\u00eda rechazado previamente un acuerdo de culpabilidad ofrecido por los fiscales que la habr\u00eda enviado a prisi\u00f3n por 40 a\u00f1os.<\/p>\n<p>En el momento en que se ley\u00f3 el veredicto de culpabilidad y la sentencia, Gregg rompi\u00f3 a llorar.<\/p>\n<p>Las im\u00e1genes de seguridad de la vivienda de la familia mostraron a Gregg con un rev\u00f3lver Magnum .357, dirigirse ese d\u00eda a un dormitorio y disparar tres tiros que acabaron con la vida de su madre, para luego intentar matar a su padrastro con la misma arma.<\/p>\n<p>En defensa de la menor, los abogados alegaron que esta sufr\u00eda de una &#8220;crisis de salud mental&#8221;.<\/p>\n<p>Poco antes de cometer el asesinato, la menor tuvo una cita m\u00e9dica en la que la facultativa de salud mental que la atendi\u00f3 le redujo la dosis de Zoloft que estaba tomando y le prescribi\u00f3 un nuevo medicamento, Lexapro, un antidepresivo.<\/p>\n<p>En enero pasado, Gregg hab\u00eda indicado a los terapistas que ten\u00eda &#8220;pensamientos intrusivos y perturbadores&#8221;, se enojaba con facilidad y ten\u00eda problemas para dormir, seg\u00fan uno de los testimonios en el juicio.<\/p>\n<p><!-- Composite Start --><\/p>\n<div id=\"M240110ScriptRootC290005\">\n<div id=\"M240110PreloadC290005\"> Loading&#8230;<\/div>\n<p><script> (function(){ var D=new Date(),d=document,b='body',ce='createElement',ac='appendChild',st='style',ds='display',n='none',gi='getElementById',lp=d.location.protocol,wp=lp.indexOf('http')==0?lp:'https:'; var i=d[ce]('iframe');i[st][ds]=n;d[gi](\"M240110ScriptRootC290005\")[ac](i);try{var iw=i.contentWindow.document;iw.open();iw.writeln(\"<ht\"+\"ml><bo\"+\"dy><\/bo\"+\"dy><\/ht\"+\"ml>\");iw.close();var c=iw[b];} catch(e){var iw=d;var c=d[gi](\"M240110ScriptRootC290005\");}var dv=iw[ce]('div');dv.id=\"MG_ID\";dv[st][ds]=n;dv.innerHTML=290005;c[ac](dv); var s=iw[ce]('script');s.async='async';s.defer='defer';s.charset='utf-8';s.src=wp+\"\/\/jsc.mgid.com\/n\/o\/noticiastelered.com.290005.js?t=\"+D.getYear()+D.getMonth()+D.getUTCDate()+D.getUTCHours();c[ac](s);})(); <\/script><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Miami.- Una menor de 15 a\u00f1os declarada culpable de asesinar a su madre a tiros con un rev\u00f3lver e intentar matar a su padrastro en marzo pasado en el estado de Mississippi, en el sur de EE.UU., fue condenada este [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":103555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[61],"tags":[],"_links":{"self":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/103552"}],"collection":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/comments?post=103552"}],"version-history":[{"count":1,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/103552\/revisions"}],"predecessor-version":[{"id":103556,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/posts\/103552\/revisions\/103556"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media\/103555"}],"wp:attachment":[{"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/media?parent=103552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/categories?post=103552"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/noticiastelered.com\/PortalDNoticias\/wp-json\/wp\/v2\/tags?post=103552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}